{"id":6059,"date":"2024-04-13T16:23:59","date_gmt":"2024-04-13T14:23:59","guid":{"rendered":"https:\/\/dominiquedorla.re\/?p=6059"},"modified":"2026-05-27T11:50:11","modified_gmt":"2026-05-27T09:50:11","slug":"cascades-dominique-dorla","status":"publish","type":"post","link":"https:\/\/dominiquedorla.re\/en\/cascades-dominique-dorla\/","title":{"rendered":"\u00ab\u00a0Cascades\u00a0\u00bb de Dominique Dorla, acquis par la R\u00e9gion R\u00e9union"},"content":{"rendered":"<div class=\"vc_row wpb_row vc_row-fluid vc_custom_1539159563009\" ><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Cascades de Dominique Dorla rejoint le fonds d&rsquo;art contemporain de la R\u00e9gion R\u00e9union. La collectivit\u00e9 avait lanc\u00e9 un appel \u00e0 candidature sur le th\u00e8me Patrimoine et Histoire de la R\u00e9union. Elle a finalement retenu cette \u0153uvre pour enrichir sa collection.<\/p>\n<p>Il s&rsquo;agit d&rsquo;un paysage de cascades compos\u00e9 d&rsquo;un assemblage de dix fragments huile sur toile pour une dimension de 90 X 173 cm. Au-dessus, un triangle isoc\u00e8le de 173 cm de base sur 45 cm de hauteur \u00e9voque le toit d&rsquo;une case cr\u00e9ole. Il encadre une huile sur contreplaqu\u00e9 d&rsquo;un style radicalement diff\u00e9rent surplombant les cascades.<\/p>\n<blockquote>\n<p style=\"text-align: left;\">\u00a0\u00bb Le fractionnement de la repr\u00e9sentation donne un caract\u00e8re particulier en ce sens que le regard peut tant\u00f4t appr\u00e9hender la globalit\u00e9 de l\u2019\u0153uvre ou bien se laisser happer par ces points d&rsquo;ancrage qui lui proposent de voyager s\u00e9par\u00e9ment dans chaque petit univers. Les notes color\u00e9es sous cette peinture globalement ex\u00e9cut\u00e9e en d\u00e9grad\u00e9s de gris sont dues \u00e0 une premi\u00e8re intervention polychrome qui en constitue le lit et sublime les gris qui la jouxtent ou la recouvrent par une richesse de nuances suppl\u00e9mentaires. La structure porteuse rouge vif en forme de \u00ab\u00a0petite chapelle\u00a0\u00bb affirme les origines de l\u2019\u0153uvre tout en lui donnant une dimension mystique.\u00a0\u00bb<\/p>\n<\/blockquote>\n<p>Les photographies ci-dessous \u00e9clairent la gen\u00e8se du tableau, les techniques employ\u00e9es et la d\u00e9marche de l&rsquo;artiste. L&rsquo;\u0153uvre a ensuite rejoint l&rsquo;H\u00f4tel de R\u00e9gion le 12 mars. Pour l&rsquo;occasion, un petit reportage photo a gard\u00e9 une trace de l&rsquo;\u00e9v\u00e9nement.<\/p>\n<h2 class=\"text-text-100 mt-3 -mb-1 text-&#091;1.125rem&#093; font-bold\">Qui est Dominique Dorla ?<\/h2>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-&#091;1.7&#093;\">N\u00e9e \u00e0 Saint-Paul en 1973, Dominique Dorla est une artiste cr\u00e9ole cot\u00e9e install\u00e9e \u00e0 La R\u00e9union. Vous pouvez retrouver son parcours complet sur sa <a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"https:\/\/dominiquedorla.re\/en\/biographie\/\">biographie<\/a>. Peintre et sculptrice, elle a aussi expos\u00e9 en m\u00e9tropole, \u00e0 Maurice, en Chine et aux \u00c9mirats arabes unis. Pour <a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"https:\/\/dominiquedorla.re\/en\/series\/\">voir son travail<\/a>, parcourez ses diff\u00e9rentes s\u00e9ries. Vous pouvez aussi d\u00e9couvrir ses autres cr\u00e9ations \u00e0 <a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"https:\/\/lakazartson.re\/\" target=\"_blank\" rel=\"noopener\">La Kaz Art &amp; Son<\/a>.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1539160214379\" ><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 33px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n<div class=\"vc_grid-container-wrapper vc_clearfix vc_grid-animation-zoomIn\">\n\t<div class=\"vc_grid-container vc_clearfix wpb_content_element vc_masonry_media_grid\" data-initial-loading-animation=\"zoomIn\" data-vc-grid-settings=\"{&quot;page_id&quot;:6059,&quot;style&quot;:&quot;all-masonry&quot;,&quot;action&quot;:&quot;vc_get_vc_grid_data&quot;,&quot;shortcode_id&quot;:&quot;1779875345082-a061f937-ca66-0&quot;,&quot;tag&quot;:&quot;vc_masonry_media_grid&quot;}\" data-vc-request=\"https:\/\/dominiquedorla.re\/wp-admin\/admin-ajax.php\" data-vc-post-id=\"6059\" data-vc-public-nonce=\"0abb8aff2f\">\n\t\t\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"Cascades de Dominique Dorla rejoint le fonds d'art contemporain de la R\u00e9gion R\u00e9union. La collectivit\u00e9 avait lanc\u00e9 un appel \u00e0 candidature sur le th\u00e8me Patrimoine et Histoire de la R\u00e9union. Elle a finalement retenu cette \u0153uvre pour enrichir sa collection. Il s'agit d'un paysage de cascades compos\u00e9 d'un assemblage de dix fragments huile sur toile pour une dimension de 90 X 173 cm. Au-dessus, un triangle isoc\u00e8le de 173 cm de base sur 45 cm [...]","protected":false},"author":2,"featured_media":6050,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6059","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cascades de Dominique Dorla, \u0153uvre acquise par la R\u00e9gion R\u00e9union<\/title>\n<meta name=\"description\" content=\"Cascades de Dominique Dorla, paysage en dix fragments huile sur toile coiff\u00e9 d&#039;une case cr\u00e9ole, rejoint le fonds d&#039;art contemporain de la R\u00e9gion R\u00e9union.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dominiquedorla.re\/en\/cascades-dominique-dorla\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cascades de Dominique Dorla, \u0153uvre acquise par la R\u00e9gion R\u00e9union\" \/>\n<meta property=\"og:description\" content=\"Cascades de Dominique Dorla, paysage en dix fragments huile sur toile coiff\u00e9 d&#039;une case cr\u00e9ole, rejoint le fonds d&#039;art contemporain de la R\u00e9gion R\u00e9union.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dominiquedorla.re\/en\/cascades-dominique-dorla\/\" \/>\n<meta property=\"og:site_name\" content=\"Dominique Dorla\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-13T14:23:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-27T09:50:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dominiquedorla.re\/wp-content\/uploads\/2024\/03\/Cascades.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1253\" \/>\n\t<meta property=\"og:image:height\" content=\"993\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michel Plane\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michel Plane\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dominiquedorla.re\\\/cascades-dominique-dorla\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dominiquedorla.re\\\/cascades-dominique-dorla\\\/\"},\"author\":{\"name\":\"Michel Plane\",\"@id\":\"https:\\\/\\\/dominiquedorla.re\\\/#\\\/schema\\\/person\\\/b353b1a0fa6c63575fb826d99e4cd7fb\"},\"headline\":\"\u00ab\u00a0Cascades\u00a0\u00bb de Dominique Dorla, acquis par la R\u00e9gion R\u00e9union\",\"datePublished\":\"2024-04-13T14:23:59+00:00\",\"dateModified\":\"2026-05-27T09:50:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dominiquedorla.re\\\/cascades-dominique-dorla\\\/\"},\"wordCount\":407,\"publisher\":{\"@id\":\"https:\\\/\\\/dominiquedorla.re\\\/#\\\/schema\\\/person\\\/8fd669491366e69e7fa3b4ce508c8c9c\"},\"image\":{\"@id\":\"https:\\\/\\\/dominiquedorla.re\\\/cascades-dominique-dorla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dominiquedorla.re\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Cascades.jpg\",\"articleSection\":[\"Actualit\u00e9\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dominiquedorla.re\\\/cascades-dominique-dorla\\\/\",\"url\":\"https:\\\/\\\/dominiquedorla.re\\\/cascades-dominique-dorla\\\/\",\"name\":\"Cascades de Dominique Dorla, \u0153uvre acquise par la R\u00e9gion R\u00e9union\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dominiquedorla.re\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dominiquedorla.re\\\/cascades-dominique-dorla\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dominiquedorla.re\\\/cascades-dominique-dorla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dominiquedorla.re\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Cascades.jpg\",\"datePublished\":\"2024-04-13T14:23:59+00:00\",\"dateModified\":\"2026-05-27T09:50:11+00:00\",\"description\":\"Cascades de Dominique Dorla, paysage en dix fragments huile sur toile coiff\u00e9 d'une case cr\u00e9ole, rejoint le fonds d'art contemporain de la R\u00e9gion R\u00e9union.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dominiquedorla.re\\\/cascades-dominique-dorla\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dominiquedorla.re\\\/cascades-dominique-dorla\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dominiquedorla.re\\\/cascades-dominique-dorla\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dominiquedorla.re\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Cascades.jpg\",\"contentUrl\":\"https:\\\/\\\/dominiquedorla.re\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Cascades.jpg\",\"width\":1253,\"height\":993,\"caption\":\"Cascades de Dominique Dorla\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dominiquedorla.re\\\/cascades-dominique-dorla\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dominiquedorla.re\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00ab\u00a0Cascades\u00a0\u00bb de Dominique Dorla, acquis par la R\u00e9gion R\u00e9union\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dominiquedorla.re\\\/#website\",\"url\":\"https:\\\/\\\/dominiquedorla.re\\\/\",\"name\":\"Dominique Dorla\",\"description\":\"Artiste peintre cr\u00e9ole install\u00e9e \u00e0 l&#039;\u00eele de la R\u00e9union, cr\u00e9atrice du motif \u00ab Yaya \u00bb. Peinture contemporaine cr\u00e9ole, sculpture et arts plastiques. Cot\u00e9e officiellement apr\u00e8s une vente \u00e0 l&#039;H\u00f4tel Drouot (Paris, 2018).\",\"publisher\":{\"@id\":\"https:\\\/\\\/dominiquedorla.re\\\/#\\\/schema\\\/person\\\/8fd669491366e69e7fa3b4ce508c8c9c\"},\"alternateName\":\"DORLA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dominiquedorla.re\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/dominiquedorla.re\\\/#\\\/schema\\\/person\\\/8fd669491366e69e7fa3b4ce508c8c9c\",\"name\":\"Dominique Dorla\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dominiquedorla.re\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/dominiquebio.jpg\",\"url\":\"https:\\\/\\\/dominiquedorla.re\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/dominiquebio.jpg\",\"contentUrl\":\"https:\\\/\\\/dominiquedorla.re\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/dominiquebio.jpg\",\"width\":700,\"height\":878,\"caption\":\"Dominique Dorla\"},\"logo\":{\"@id\":\"https:\\\/\\\/dominiquedorla.re\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/dominiquebio.jpg\"},\"description\":\"Dominique Dorla est une artiste peintre cr\u00e9ole install\u00e9e \u00e0 l\u2019\u00eele de la R\u00e9union. Principalement peintre, elle est aussi sculptrice et plasticienne, et explore de nombreux m\u00e9diums : fresque, linogravure, digigraphie, c\u00e9ramique. Ses \u0153uvres ont \u00e9t\u00e9 expos\u00e9es \u00e0 La R\u00e9union, \u00e0 l\u2019\u00eele Maurice, en Chine, aux \u00c9mirats arabes unis et en France m\u00e9tropolitaine, o\u00f9 son passage \u00e0 l\u2019H\u00f4tel Drouot lui a valu une cote officielle.\",\"sameAs\":[\"https:\\\/\\\/dominiquedorla.re\\\/\",\"https:\\\/\\\/www.instagram.com\\\/domi.dorla_artiste\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/dominique-dorla-3b5529167\\\/\",\"https:\\\/\\\/www.wikidata.org\\\/wiki\\\/Q140309845\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dominiquedorla.re\\\/#\\\/schema\\\/person\\\/b353b1a0fa6c63575fb826d99e4cd7fb\",\"name\":\"Michel Plane\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dfb83b57a1dedfc60afff5397d741221e4d6f923375a8760fd431b9e05b71041?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dfb83b57a1dedfc60afff5397d741221e4d6f923375a8760fd431b9e05b71041?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dfb83b57a1dedfc60afff5397d741221e4d6f923375a8760fd431b9e05b71041?s=96&d=mm&r=g\",\"caption\":\"Michel Plane\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cascades de Dominique Dorla, \u0153uvre acquise par la R\u00e9gion R\u00e9union","description":"Cascades de Dominique Dorla, paysage en dix fragments huile sur toile coiff\u00e9 d'une case cr\u00e9ole, rejoint le fonds d'art contemporain de la R\u00e9gion R\u00e9union.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dominiquedorla.re\/en\/cascades-dominique-dorla\/","og_locale":"en_US","og_type":"article","og_title":"Cascades de Dominique Dorla, \u0153uvre acquise par la R\u00e9gion R\u00e9union","og_description":"Cascades de Dominique Dorla, paysage en dix fragments huile sur toile coiff\u00e9 d'une case cr\u00e9ole, rejoint le fonds d'art contemporain de la R\u00e9gion R\u00e9union.","og_url":"https:\/\/dominiquedorla.re\/en\/cascades-dominique-dorla\/","og_site_name":"Dominique Dorla","article_published_time":"2024-04-13T14:23:59+00:00","article_modified_time":"2026-05-27T09:50:11+00:00","og_image":[{"width":1253,"height":993,"url":"https:\/\/dominiquedorla.re\/wp-content\/uploads\/2024\/03\/Cascades.jpg","type":"image\/jpeg"}],"author":"Michel Plane","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Michel Plane","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dominiquedorla.re\/cascades-dominique-dorla\/#article","isPartOf":{"@id":"https:\/\/dominiquedorla.re\/cascades-dominique-dorla\/"},"author":{"name":"Michel Plane","@id":"https:\/\/dominiquedorla.re\/#\/schema\/person\/b353b1a0fa6c63575fb826d99e4cd7fb"},"headline":"\u00ab\u00a0Cascades\u00a0\u00bb de Dominique Dorla, acquis par la R\u00e9gion R\u00e9union","datePublished":"2024-04-13T14:23:59+00:00","dateModified":"2026-05-27T09:50:11+00:00","mainEntityOfPage":{"@id":"https:\/\/dominiquedorla.re\/cascades-dominique-dorla\/"},"wordCount":407,"publisher":{"@id":"https:\/\/dominiquedorla.re\/#\/schema\/person\/8fd669491366e69e7fa3b4ce508c8c9c"},"image":{"@id":"https:\/\/dominiquedorla.re\/cascades-dominique-dorla\/#primaryimage"},"thumbnailUrl":"https:\/\/dominiquedorla.re\/wp-content\/uploads\/2024\/03\/Cascades.jpg","articleSection":["Actualit\u00e9"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/dominiquedorla.re\/cascades-dominique-dorla\/","url":"https:\/\/dominiquedorla.re\/cascades-dominique-dorla\/","name":"Cascades de Dominique Dorla, \u0153uvre acquise par la R\u00e9gion R\u00e9union","isPartOf":{"@id":"https:\/\/dominiquedorla.re\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dominiquedorla.re\/cascades-dominique-dorla\/#primaryimage"},"image":{"@id":"https:\/\/dominiquedorla.re\/cascades-dominique-dorla\/#primaryimage"},"thumbnailUrl":"https:\/\/dominiquedorla.re\/wp-content\/uploads\/2024\/03\/Cascades.jpg","datePublished":"2024-04-13T14:23:59+00:00","dateModified":"2026-05-27T09:50:11+00:00","description":"Cascades de Dominique Dorla, paysage en dix fragments huile sur toile coiff\u00e9 d'une case cr\u00e9ole, rejoint le fonds d'art contemporain de la R\u00e9gion R\u00e9union.","breadcrumb":{"@id":"https:\/\/dominiquedorla.re\/cascades-dominique-dorla\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dominiquedorla.re\/cascades-dominique-dorla\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dominiquedorla.re\/cascades-dominique-dorla\/#primaryimage","url":"https:\/\/dominiquedorla.re\/wp-content\/uploads\/2024\/03\/Cascades.jpg","contentUrl":"https:\/\/dominiquedorla.re\/wp-content\/uploads\/2024\/03\/Cascades.jpg","width":1253,"height":993,"caption":"Cascades de Dominique Dorla"},{"@type":"BreadcrumbList","@id":"https:\/\/dominiquedorla.re\/cascades-dominique-dorla\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dominiquedorla.re\/"},{"@type":"ListItem","position":2,"name":"\u00ab\u00a0Cascades\u00a0\u00bb de Dominique Dorla, acquis par la R\u00e9gion R\u00e9union"}]},{"@type":"WebSite","@id":"https:\/\/dominiquedorla.re\/#website","url":"https:\/\/dominiquedorla.re\/","name":"Dominique Dorla","description":"Artiste peintre cr\u00e9ole install\u00e9e \u00e0 l&#039;\u00eele de la R\u00e9union, cr\u00e9atrice du motif \u00ab Yaya \u00bb. Peinture contemporaine cr\u00e9ole, sculpture et arts plastiques. Cot\u00e9e officiellement apr\u00e8s une vente \u00e0 l&#039;H\u00f4tel Drouot (Paris, 2018).","publisher":{"@id":"https:\/\/dominiquedorla.re\/#\/schema\/person\/8fd669491366e69e7fa3b4ce508c8c9c"},"alternateName":"DORLA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dominiquedorla.re\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/dominiquedorla.re\/#\/schema\/person\/8fd669491366e69e7fa3b4ce508c8c9c","name":"Dominique Dorla","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dominiquedorla.re\/wp-content\/uploads\/2022\/01\/dominiquebio.jpg","url":"https:\/\/dominiquedorla.re\/wp-content\/uploads\/2022\/01\/dominiquebio.jpg","contentUrl":"https:\/\/dominiquedorla.re\/wp-content\/uploads\/2022\/01\/dominiquebio.jpg","width":700,"height":878,"caption":"Dominique Dorla"},"logo":{"@id":"https:\/\/dominiquedorla.re\/wp-content\/uploads\/2022\/01\/dominiquebio.jpg"},"description":"Dominique Dorla est une artiste peintre cr\u00e9ole install\u00e9e \u00e0 l\u2019\u00eele de la R\u00e9union. Principalement peintre, elle est aussi sculptrice et plasticienne, et explore de nombreux m\u00e9diums : fresque, linogravure, digigraphie, c\u00e9ramique. Ses \u0153uvres ont \u00e9t\u00e9 expos\u00e9es \u00e0 La R\u00e9union, \u00e0 l\u2019\u00eele Maurice, en Chine, aux \u00c9mirats arabes unis et en France m\u00e9tropolitaine, o\u00f9 son passage \u00e0 l\u2019H\u00f4tel Drouot lui a valu une cote officielle.","sameAs":["https:\/\/dominiquedorla.re\/","https:\/\/www.instagram.com\/domi.dorla_artiste\/","https:\/\/www.linkedin.com\/in\/dominique-dorla-3b5529167\/","https:\/\/www.wikidata.org\/wiki\/Q140309845"]},{"@type":"Person","@id":"https:\/\/dominiquedorla.re\/#\/schema\/person\/b353b1a0fa6c63575fb826d99e4cd7fb","name":"Michel Plane","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/dfb83b57a1dedfc60afff5397d741221e4d6f923375a8760fd431b9e05b71041?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dfb83b57a1dedfc60afff5397d741221e4d6f923375a8760fd431b9e05b71041?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dfb83b57a1dedfc60afff5397d741221e4d6f923375a8760fd431b9e05b71041?s=96&d=mm&r=g","caption":"Michel Plane"}}]}},"_links":{"self":[{"href":"https:\/\/dominiquedorla.re\/en\/wp-json\/wp\/v2\/posts\/6059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dominiquedorla.re\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dominiquedorla.re\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dominiquedorla.re\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dominiquedorla.re\/en\/wp-json\/wp\/v2\/comments?post=6059"}],"version-history":[{"count":9,"href":"https:\/\/dominiquedorla.re\/en\/wp-json\/wp\/v2\/posts\/6059\/revisions"}],"predecessor-version":[{"id":6103,"href":"https:\/\/dominiquedorla.re\/en\/wp-json\/wp\/v2\/posts\/6059\/revisions\/6103"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dominiquedorla.re\/en\/wp-json\/wp\/v2\/media\/6050"}],"wp:attachment":[{"href":"https:\/\/dominiquedorla.re\/en\/wp-json\/wp\/v2\/media?parent=6059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dominiquedorla.re\/en\/wp-json\/wp\/v2\/categories?post=6059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dominiquedorla.re\/en\/wp-json\/wp\/v2\/tags?post=6059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}